{"id":575,"date":"2012-11-28T18:09:35","date_gmt":"2012-11-28T18:09:35","guid":{"rendered":"https:\/\/www.ibertronica.es\/blog\/?p=575"},"modified":"2022-03-25T15:04:42","modified_gmt":"2022-03-25T14:04:42","slug":"impresoras-un-dispositivo-con-fecha-de-caducidad","status":"publish","type":"post","link":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/","title":{"rendered":"Impresoras, \u00bfun dispositivo con fecha de caducidad?"},"content":{"rendered":"<p style=\"text-align: justify;\"><a onclick=\"javascript:pageTracker._trackPageview('\/downloads\/blog\/wp-content\/uploads\/2012\/11\/Impresora.jpg');\"  href=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/11\/Impresora.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1829 size-full\" title=\"Impresora\" src=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/11\/Impresora.jpg\" alt=\"\" width=\"216\" height=\"216\" srcset=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/11\/Impresora.jpg 216w, https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/11\/Impresora-150x150.jpg 150w, https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/11\/Impresora-55x55.jpg 55w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/a>El paso del tiempo no perdona para el sector de la inform\u00e1tica, donde hay productos y dispositivos que encuentran una elevada utilidad en un momento determinado, pero que pueden pasar a segundo plano con el progreso de los a\u00f1os. Lo que comenz\u00f3 siendo una revoluci\u00f3n en su tiempo, como el uso de ratones, poco a poco ha ca\u00eddo en saco roto y se est\u00e1n dejando cada vez m\u00e1s de lado. <strong>Lo mismo est\u00e1 ocurriendo con las impresoras, que se han convertido en el foco de atenci\u00f3n de millones de personas que tienen costumbre de realizar impresiones<\/strong> de forma habitual para el trabajo o su d\u00eda a d\u00eda. Pero por lo que parece, los d\u00edas en los que las <a onclick=\"javascript:pageTracker._trackPageview('\/outgoing\/en.wikipedia.org\/wiki\/Printer_(computing)');\" title=\"Impresoras en la inform\u00e1tica\"  href=\"https:\/\/en.wikipedia.org\/wiki\/Printer_(computing)\" target=\"_blank\" rel=\"noopener\">impresoras<\/a> reinaban, est\u00e1 cerca de llegar a su final.<\/p>\n<p>En el mercado hay numerosos tipos de impresoras, puedes ver la disponibles en nuestro cat\u00e1logo desde este <a href=\"https:\/\/ibertronica.es\/perifericos\/perifericos-perifericos\/impresoras\">link<\/a>.<\/p>\n<h2>Las empresas mandan<\/h2>\n<p>El mundo de las empresas, nexo donde se tiende a buscar las principales soluciones de ahorro, est\u00e1 demostrando que es importante quitarse de encima cuantas m\u00e1s impresoras sea posible para ahorrar. <strong>Las estad\u00edsticas reveladas por compa\u00f1\u00edas como Lexmark dejan claro que el mercado de las impresoras se est\u00e1 reduciendo<\/strong> y que poco a poco se impone buscar alternativas al uso del papel. Estamos lejos de haber llegado a la experiencia de uso libre de papel que se promet\u00eda a\u00f1os atr\u00e1s, pero es cierto que s\u00ed se est\u00e1 reduciendo de forma progresiva, aunque pausada. Algunos departamentos gubernamentales, como el Departamento de Veteranos de los Estados Unidos, <strong>han llevado a cabo reducciones en cuanto a impresoras disponibles, consiguiendo un importante ahorro en su presupuesto<\/strong>.<\/p>\n<p style=\"text-align: center;\"><a onclick=\"javascript:pageTracker._trackPageview('\/downloads\/blog\/wp-content\/uploads\/images\/Impresora_imprimiendo.jpg');\"  href=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/images\/Impresora_imprimiendo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Imprimir documentos con una impresora en un equipo PC\" src=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/images\/Impresora_imprimiendo.jpg\" alt=\"Impresoras para ordenadores PC\" width=\"401\" height=\"376\" \/><\/a><\/p>\n<h2>Qu\u00e9 se puede hacer<\/h2>\n<p>La pregunta que se formulan muchos usuarios, a la vista del ahorro estad\u00edstico que supone el dejar de usar las impresoras. Es qu\u00e9 pueden hacer para ahorrar este dinero y apoyar a que cada vez el uso de papel sea menor. <strong>Una idea pasa por, si tenemos una impresora en casa y otra en la oficina, eliminar una de las dos y hacer uso de la soluci\u00f3n ePrint de HP.<\/strong> Para poder usar la que nos quedemos de forma c\u00f3moda. Es decir, con esta soluci\u00f3n enviamos un correo electr\u00f3nico a la impresora del trabajo y esta lo imprime aunque nos encontremos en casa.<\/p>\n<p>La recomendaci\u00f3n clara es almacenar los documentos en formato PDF. <strong>Un conversor como doPDF puede ser muy \u00fatil, y la mayor\u00eda de dispositivos m\u00f3viles son compatibles con este formato de archivos<\/strong>, por lo que podemos llevar los documentos a cualquier lugar. En este sentido tambi\u00e9n se recomienda Evernote, que sincroniza los docs de casa y la oficina con el dispositivo m\u00f3vil que estemos utilizando. Si hablamos del env\u00edo de fax, un servicio como el de FaxZero <strong>permite enviar un documento como fax a cualquier l\u00ednea tradicional de este dispositivo<\/strong>. La versi\u00f3n gratuita a\u00f1ade un membrete a cada mensaje enviado, pero por un coste reducido se puede eliminar.<\/p>\n<p><strong>Este tipo de opciones permiten que dejemos de depender tanto de las impresoras, aunque existen muchos otros sistemas e ideas que se pueden llevar a cabo<\/strong>. En el caso de requerir la firma de una carta o contrato, el usuario puede tener su firma escaneada y simplemente cortarla y pegarla sobre el fondo blanco del documento, ahorr\u00e1ndose no s\u00f3lo el papel y la tinta, sino el tiempo del proceso de escaneado posterior.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"La impresi\u00f3n en nube es una tendencia del sector\" src=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/images\/Imprimir_desde_la_nube.jpg\" alt=\"Imprimir desde nube\" width=\"400\" height=\"269\" \/><\/p>\n<h2>Las tendencias de mercado sobre impresoras<\/h2>\n<p>Lo que ocurre con las impresoras es similar a lo que est\u00e1 ocurriendo en general en el mercado, que <strong>apuesta cada vez por el soporte digital y menos por las tradiciones instauradas por los primeros sistemas inform\u00e1ticos<\/strong>. Si el software cada vez se edita menos en formato f\u00edsico, opt\u00e1ndose por su distribuci\u00f3n digital. Al igual que est\u00e1 ocurriendo con la m\u00fasica o el v\u00eddeo, los documentos tambi\u00e9n est\u00e1n pasando a ocupar puestos de relevancia en formatos digitales.<\/p>\n<p>Dicen los expertos y analistas, que el mercado no se encuentra tan lejos del d\u00eda en el que sea una costumbre disponer de una memoria stick personalizada u otro sistema de almacenamiento de conexi\u00f3n r\u00e1pida <strong>en el que llevaremos guardados todos nuestros datos personales, desde la identificaci\u00f3n personal.<\/strong> Hasta el pasaporte o cualquier otro archivo que necesite compartir. Esto significar\u00eda el final definitivo del sector de las impresoras, en el que las cifras de ventas cada vez son m\u00e1s reducidas. Aunque pese a los negocios que se dedican a la venta de cartuchos de tinta, un negocio en alza que se espera entre en decadencia antes o despu\u00e9s.<\/p>\n<p><a href=\"https:\/\/ibertronica.es\/perifericos\/perifericos-perifericos\/impresoras\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12353 size-full\" title=\"BannerComprarBlog\" src=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/08\/BannerComprarBlog.jpg\" alt=\"Comprar impresoras\" width=\"1227\" height=\"285\" srcset=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/08\/BannerComprarBlog.jpg 1227w, https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/08\/BannerComprarBlog-300x70.jpg 300w, https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/08\/BannerComprarBlog-1024x238.jpg 1024w, https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/08\/BannerComprarBlog-150x35.jpg 150w, https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/08\/BannerComprarBlog-228x53.jpg 228w\" sizes=\"auto, (max-width: 1227px) 100vw, 1227px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El paso del tiempo no perdona para el sector de la inform\u00e1tica, donde hay productos y dispositivos que encuentran una elevada utilidad en un momento determinado, pero que pueden pasar a segundo plano con el progreso de los a\u00f1os. Lo que comenz\u00f3 siendo una revoluci\u00f3n en su tiempo, como el uso de ratones, poco a poco ha ca\u00eddo en saco roto y se est\u00e1n dejando cada vez m\u00e1s de lado. Lo mismo est\u00e1 ocurriendo con las impresoras, que se han&hellip;<\/p>\n","protected":false},"author":2,"featured_media":577,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[201,199,202,203,200],"class_list":["post-575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productos","tag-hp","tag-impresoras","tag-imprimir","tag-nube","tag-opinion","post-has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impresoras, \u00bfun dispositivo con fecha de caducidad? - Ibertronica<\/title>\n<meta name=\"description\" content=\"La utilizaci\u00f3n de impresoras est\u00e1 perdi\u00e9ndose a nivel de usuario como corporativo, podr\u00eda tratarse de un dispositivo cada vez menos usado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impresoras, \u00bfun dispositivo con fecha de caducidad? - Ibertronica\" \/>\n<meta property=\"og:description\" content=\"La utilizaci\u00f3n de impresoras est\u00e1 perdi\u00e9ndose a nivel de usuario como corporativo, podr\u00eda tratarse de un dispositivo cada vez menos usado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de tecnolog\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IbertronicaES\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-28T18:09:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-25T14:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"magazine\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"magazine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\"},\"author\":{\"name\":\"magazine\",\"@id\":\"https:\/\/ibertronica.es\/blog\/#\/schema\/person\/d47e9d93bc56d014002fd59d2e1cb9c1\"},\"headline\":\"Impresoras, \u00bfun dispositivo con fecha de caducidad?\",\"datePublished\":\"2012-11-28T18:09:35+00:00\",\"dateModified\":\"2022-03-25T14:04:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\"},\"wordCount\":802,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg\",\"keywords\":[\"HP\",\"impresoras\",\"imprimir\",\"nube\",\"opini\u00f3n\"],\"articleSection\":[\"Productos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\",\"url\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\",\"name\":\"Impresoras, \u00bfun dispositivo con fecha de caducidad? - Ibertronica\",\"isPartOf\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg\",\"datePublished\":\"2012-11-28T18:09:35+00:00\",\"dateModified\":\"2022-03-25T14:04:42+00:00\",\"description\":\"La utilizaci\u00f3n de impresoras est\u00e1 perdi\u00e9ndose a nivel de usuario como corporativo, podr\u00eda tratarse de un dispositivo cada vez menos usado.\",\"breadcrumb\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage\",\"url\":\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg\",\"contentUrl\":\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg\",\"width\":600,\"height\":330,\"caption\":\"Impresoras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/ibertronica.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impresoras, \u00bfun dispositivo con fecha de caducidad?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ibertronica.es\/blog\/#website\",\"url\":\"https:\/\/ibertronica.es\/blog\/\",\"name\":\"Blog de tecnolog\u00eda\",\"description\":\"Ibertr\u00f3nica, un blog sobre hardware inform\u00e1tico y servidores para todo tipo de prestaciones\",\"publisher\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ibertronica.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ibertronica.es\/blog\/#organization\",\"name\":\"Sistemas Ibertr\u00f3nica\",\"url\":\"https:\/\/ibertronica.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ibertronica.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/03\/logotipo_web_2019-1.png\",\"contentUrl\":\"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/03\/logotipo_web_2019-1.png\",\"width\":417,\"height\":45,\"caption\":\"Sistemas Ibertr\u00f3nica\"},\"image\":{\"@id\":\"https:\/\/ibertronica.es\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/IbertronicaES\/\",\"https:\/\/x.com\/Ibertronica_Es\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/ibertronica.es\/blog\/#\/schema\/person\/d47e9d93bc56d014002fd59d2e1cb9c1\",\"name\":\"magazine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ibertronica.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d1ae06745040f270e4f310dafae96f9bc6d960c810d653ac06972e979569589?s=96&d=https%3A%2F%2Fwww.ibertronica.es%2Fimages%2Fperfil-azul.jpg&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d1ae06745040f270e4f310dafae96f9bc6d960c810d653ac06972e979569589?s=96&d=https%3A%2F%2Fwww.ibertronica.es%2Fimages%2Fperfil-azul.jpg&r=g\",\"caption\":\"magazine\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impresoras, \u00bfun dispositivo con fecha de caducidad? - Ibertronica","description":"La utilizaci\u00f3n de impresoras est\u00e1 perdi\u00e9ndose a nivel de usuario como corporativo, podr\u00eda tratarse de un dispositivo cada vez menos usado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/","og_locale":"es_ES","og_type":"article","og_title":"Impresoras, \u00bfun dispositivo con fecha de caducidad? - Ibertronica","og_description":"La utilizaci\u00f3n de impresoras est\u00e1 perdi\u00e9ndose a nivel de usuario como corporativo, podr\u00eda tratarse de un dispositivo cada vez menos usado.","og_url":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/","og_site_name":"Blog de tecnolog\u00eda","article_publisher":"https:\/\/www.facebook.com\/IbertronicaES\/","article_published_time":"2012-11-28T18:09:35+00:00","article_modified_time":"2022-03-25T14:04:42+00:00","og_image":[{"width":600,"height":330,"url":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg","type":"image\/jpeg"}],"author":"magazine","twitter_misc":{"Escrito por":"magazine","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#article","isPartOf":{"@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/"},"author":{"name":"magazine","@id":"https:\/\/ibertronica.es\/blog\/#\/schema\/person\/d47e9d93bc56d014002fd59d2e1cb9c1"},"headline":"Impresoras, \u00bfun dispositivo con fecha de caducidad?","datePublished":"2012-11-28T18:09:35+00:00","dateModified":"2022-03-25T14:04:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/"},"wordCount":802,"commentCount":0,"publisher":{"@id":"https:\/\/ibertronica.es\/blog\/#organization"},"image":{"@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage"},"thumbnailUrl":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg","keywords":["HP","impresoras","imprimir","nube","opini\u00f3n"],"articleSection":["Productos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/","url":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/","name":"Impresoras, \u00bfun dispositivo con fecha de caducidad? - Ibertronica","isPartOf":{"@id":"https:\/\/ibertronica.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage"},"image":{"@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage"},"thumbnailUrl":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg","datePublished":"2012-11-28T18:09:35+00:00","dateModified":"2022-03-25T14:04:42+00:00","description":"La utilizaci\u00f3n de impresoras est\u00e1 perdi\u00e9ndose a nivel de usuario como corporativo, podr\u00eda tratarse de un dispositivo cada vez menos usado.","breadcrumb":{"@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#primaryimage","url":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg","contentUrl":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2012\/12\/Impresoras.jpg","width":600,"height":330,"caption":"Impresoras"},{"@type":"BreadcrumbList","@id":"https:\/\/ibertronica.es\/blog\/productos\/impresoras-un-dispositivo-con-fecha-de-caducidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ibertronica.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Impresoras, \u00bfun dispositivo con fecha de caducidad?"}]},{"@type":"WebSite","@id":"https:\/\/ibertronica.es\/blog\/#website","url":"https:\/\/ibertronica.es\/blog\/","name":"Blog de tecnolog\u00eda","description":"Ibertr\u00f3nica, un blog sobre hardware inform\u00e1tico y servidores para todo tipo de prestaciones","publisher":{"@id":"https:\/\/ibertronica.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibertronica.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ibertronica.es\/blog\/#organization","name":"Sistemas Ibertr\u00f3nica","url":"https:\/\/ibertronica.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibertronica.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/03\/logotipo_web_2019-1.png","contentUrl":"https:\/\/ibertronica.es\/blog\/wp-content\/uploads\/2020\/03\/logotipo_web_2019-1.png","width":417,"height":45,"caption":"Sistemas Ibertr\u00f3nica"},"image":{"@id":"https:\/\/ibertronica.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IbertronicaES\/","https:\/\/x.com\/Ibertronica_Es"]},{"@type":"Person","@id":"https:\/\/ibertronica.es\/blog\/#\/schema\/person\/d47e9d93bc56d014002fd59d2e1cb9c1","name":"magazine","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibertronica.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7d1ae06745040f270e4f310dafae96f9bc6d960c810d653ac06972e979569589?s=96&d=https%3A%2F%2Fwww.ibertronica.es%2Fimages%2Fperfil-azul.jpg&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d1ae06745040f270e4f310dafae96f9bc6d960c810d653ac06972e979569589?s=96&d=https%3A%2F%2Fwww.ibertronica.es%2Fimages%2Fperfil-azul.jpg&r=g","caption":"magazine"}}]}},"_links":{"self":[{"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/posts\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/comments?post=575"}],"version-history":[{"count":8,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/posts\/575\/revisions"}],"predecessor-version":[{"id":14489,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/posts\/575\/revisions\/14489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/media\/577"}],"wp:attachment":[{"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/categories?post=575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibertronica.es\/blog\/wp-json\/wp\/v2\/tags?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}